{"id":643,"date":"2023-03-27T16:04:22","date_gmt":"2023-03-27T16:04:22","guid":{"rendered":"https:\/\/brightsign2425.wpenginepowered.com\/?page_id=643"},"modified":"2025-11-10T19:07:41","modified_gmt":"2025-11-11T00:07:41","slug":"software","status":"publish","type":"page","link":"https:\/\/www.brightsign.biz\/it\/brightsign-players\/software\/","title":{"rendered":"Software"},"content":{"rendered":"<section\n  id=\"hero-block_bbd70f1cb6c0b94cb1e08acbc0619d61\"\n  class=\"hero custom-block\"\n  data-form-url=\"\"\n>\n  <!-- Backgrounds: cover full section, center position (extended via SCSS) -->\n        <div id=\"hero-desktop-background\" style=\"background-image: url('https:\/\/www.brightsign.biz\/wp-content\/uploads\/2024\/12\/Cloud-Web-Hero_1920x711px-1.png'); background-size: cover; background-position: center center; background-repeat: no-repeat;\"><\/div>\n        <div id=\"hero-mobile-background\" style=\"background-image: url('https:\/\/www.brightsign.biz\/wp-content\/uploads\/2024\/12\/Cloud-Mobile-Hero_818x1080px-1122x900.png'); background-size: cover; background-position: center center; background-repeat: no-repeat;\"><\/div>\n  \n  <div class=\"hero-gradient\" aria-hidden=\"true\"><\/div>\n  <div class=\"block-inner medium\">\n    <div class=\"block-inner-content grid-x grid-margin-y\">\n\n      <!-- MOBILE-only layout -->\n      <div class=\"cell small-12 show-for-small-only\">\n        \n        \n        \n        \n        <ul class=\"custom-breadcrumb\"><li>Prodotti e software<\/li><\/ul><div class=\"mobile-content form-content\"><h1 style=\"text-transform: none\"><strong>SERVIZI<\/strong><\/h1>\n<p>Suite di soluzioni scalabili per la gestione sicura del digital signage.<\/p>\n<\/div>      <\/div>\n      <!-- end MOBILE-only -->\n\n      <!-- DESKTOP text cell -->\n      <div class=\"cell small-12 medium-12 large-10 hide-for-small-only\">\n        \n        <ul class=\"custom-breadcrumb\"><li>Prodotti e software<\/li><\/ul><h1 style=\"text-transform: none\"><strong>SERVIZI<\/strong><\/h1>\n<p>Suite di soluzioni scalabili per la gestione sicura del digital signage.<\/p>\n      <\/div>\n      <!-- end DESKTOP text cell -->\n\n      <!-- DESKTOP form\/video cell -->\n      <div class=\"cell small-12 medium-12 large-6 center-play hide-for-small-only\">\n        \n              <\/div>\n      <!-- end DESKTOP form\/video cell -->\n\n    <\/div><!-- .block-inner-content -->\n  <\/div><!-- .block-inner -->\n<\/section><!-- hero -->\n\n\n<section id=\"why\" class=\"purple-cta-grid custom-block dark small-top none-bottom\">\n    <div class=\"block-inner medium\">\n        <div class=\"grid-x purple-cta-text-grid\">\n            <div class=\"large-8 purple-cta-text\">\n                \n                                    <p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-24736\" role=\"img\" src=\"https:\/\/www.brightsign.biz\/wp-content\/uploads\/2025\/04\/BSN.Cloud-Solution-Family_horizontal.svg\" alt=\"BrightSign BSN.Cloud soluzione\" width=\"784\" height=\"91\" \/><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center\">La vostra azienda \u00e8 in grado di gestire e scalare in modo efficiente le reti di segnaletica, da un solo lettore a migliaia, grazie a software e servizi connessi al cloud, progettati per un funzionamento senza interruzioni in qualsiasi momento e ovunque.<\/p>\n                            <\/div>\n        <\/div>\n                    <div class=\"grid-x grid-margin-x purple-repeater-grid\">\n                                    <div class=\"large-6 cell\">\n                        <div class=\"repeater-single-inner\">\n                                                            <h4 class=\"cta-grid-header\">Software all-in-one<\/h4>\n                            \n                                                            <div class=\"cta-grid-text\">\n                                    <p>Semplificate la gestione della segnaletica con brightAuthor connected e bsn.Control, entrambi gratuiti con ogni lettore BrightSign. Scegliete il vostro sistema di gestione dei contenuti (CMS) ideale collegato al cloud: bsn.Content o una soluzione di un partner affidabile.<\/p>\n                                <\/div>\n                                                    <\/div>\n                    <\/div>\n                                    <div class=\"large-6 cell\">\n                        <div class=\"repeater-single-inner\">\n                                                            <h4 class=\"cta-grid-header\">Connettivit\u00e0 affidabile<\/h4>\n                            \n                                                            <div class=\"cta-grid-text\">\n                                    <p>La connettivit\u00e0 cloud sicura e sempre attiva, alimentata da BrightSignOS\u2122, garantisce la massima tranquillit\u00e0.  Ogni lettore BrightSign \u00e8 costruito per garantire prestazioni e viene fornito con il nostro affidabile sistema operativo, che vi connette alla nostra suite completa di servizi BSN.Cloud.<\/p>\n                                <\/div>\n                                                    <\/div>\n                    <\/div>\n                                    <div class=\"large-6 cell\">\n                        <div class=\"repeater-single-inner\">\n                                                            <h4 class=\"cta-grid-header\">Gestione scalabile<\/h4>\n                            \n                                                            <div class=\"cta-grid-text\">\n                                    <p>Che si tratti della gestione di un singolo schermo o di una rete estesa, i nostri strumenti di gestione remota sono in grado di adattarsi alle vostre esigenze. Progettate, distribuite e controllate facilmente i contenuti della vostra rete, da qualsiasi luogo.<\/p>\n                                <\/div>\n                                                    <\/div>\n                    <\/div>\n                                    <div class=\"large-6 cell\">\n                        <div class=\"repeater-single-inner\">\n                                                            <h4 class=\"cta-grid-header\">Integrazione perfetta<\/h4>\n                            \n                                                            <div class=\"cta-grid-text\">\n                                    <p>I lettori BrightSign si integrano perfettamente con un'ampia gamma di piattaforme CMS tramite brightAuthor connected. Scegliete una soluzione partner che si adatti alle vostre esigenze e che garantisca prestazioni e sicurezza elevate.<\/p>\n                                <\/div>\n                                                    <\/div>\n                    <\/div>\n                            <\/div>\n            <\/div>\n<\/section>\n\n\n\n\n<section id=\"video\" class=\"media-text custom-block dark none-top none-bottom\" >\n    <div class=\"dot-in\"><\/div><!-- dot-in -->\n    <div class=\"block-inner medium grid-x right\">\n    \n        <div class=\"cell small-12 medium-12 large-6 mediatext-content default-checks\">\n            <div aria-hidden=\"true\" class=\"blue-dot\"><\/div>\n                            <h4>Riprendetevi la visibilit\u00e0 e il controllo<\/h4>\n                                                    <p>BrightSign <strong>bsn.Control<\/strong> offre una piattaforma completa che eleva il digital signage evitando i colli di bottiglia AV. \u00c8 possibile gestire e distribuire facilmente i contenuti sulla rete di display per la segnaletica, monitorare lo stato di salute dei lettori multimediali e scaricare senza problemi il software pi\u00f9 recente che mantiene i display sicuri e potenti. Non importa se i contenuti vengono gestiti localmente o tramite cloud, l'bsn.Control \u00e8 la piattaforma scalabile per le vostre esigenze di segnaletica. <strong>libero<\/strong> con ogni giocatore.<\/p>\n<p>Per le visite guidate per la connessione e il funzionamento della segnaletica, <a href=\"https:\/\/www.youtube.com\/playlist?list=PL1QgAgqcnXH-xbmbw-4u5jbE40oBaJI77\" target=\"_blank\" rel=\"noopener\">visita il nostro canale YouTube<\/a>.<\/p>\n                        \n                            <div class=\"basic-button blue\">\n                    <a href=\"#services\" target=\"_blank\">\n                        SAPERNE DI PI\u00d9                    <\/a>\n                <\/div><!-- basic-cta -->\n                        \n                    <\/div><!-- mediatext-content -->\n        \n        <div class=\"cell small-12 medium-12 large-6 form-wrapper center-play\">\n                            <!-- Normal form on all devices -->\n                                                    <div class=\"mediatext-image default-bg\">\n                        <img decoding=\"async\" src=\"https:\/\/www.brightsign.biz\/wp-content\/uploads\/2025\/08\/bsn.control-end-user-video-thumbnail-aug2025-750x440.jpg\" alt=\"Guardate il video esplicativo della gestione remota dei dispositivi BrightSign e bsn.Control\" \/>\n                                            <\/div><!-- mediatext-image -->\n                                                            \n                                <!-- Video Modal Markup using hero.php classes -->\n                    <div class=\"mediagrid-modal reveal full\" id=\"video-1113315317\" data-reveal data-close-on-click=\"true\">\n                        <div class=\"mediagrid-modal-inner\">\n                            <iframe src=\"\" data-src=\"https:\/\/player.vimeo.com\/video\/1113315317?autoplay=1\" frameborder=\"0\" allowfullscreen allowtransparency allow=\"autoplay\"><\/iframe>\n                            <button class=\"close-button\" data-close aria-label=\"Chiudere la finestra modale\" type=\"button\">\n                                <i class=\"fa-sharp fa-regular fa-xmark\"><\/i>\n                            <\/button>\n                        <\/div>\n                    <\/div>\n                    <button class=\"play-modal\" data-open=\"video-1113315317\" aria-controls=\"video-1113315317\" aria-haspopup=\"dialog\" tabindex=\"0\"><\/button>\n                    <\/div><!-- form-wrapper -->\n        \n    <\/div><!-- block-inner -->\n<\/section><!-- media-text -->\n\n\n\n\n<section id=\"services\" class=\"simple-tabs-content custom-block services-tab dark small-top small-bottom\">\n\n    <div class=\"block-inner medium\">\n\n                    <div class=\"simple-tabs-header\">\n                \n                                    <div class=\"simple-tabs-subtitle\">\n                        <h3 style=\"text-align: center;font-size: 44px;color: #701896\">Suite di software e servizi<\/h3>\n                    <\/div>\n                            <\/div>\n        \n                <!-- Tabs Navigation -->\n        <!-- Tabs Navigation -->\n        <ul class=\"tabs content-tabs\" data-tabs data-active-collapse=\"false\" id=\"tabs-tabbed-content-block_3bf07619a36f09807803f87fab4e4d06\">\n                            <li class=\"tabs-title is-active basic-button default-btns\">\n                    <a href=\"#tabID-block_3bf07619a36f09807803f87fab4e4d06-1\">bsn.Control<\/a>\n                <\/li>\n                            <li class=\"tabs-title idle basic-button default-btns\">\n                    <a href=\"#tabID-block_3bf07619a36f09807803f87fab4e4d06-2\">bsn.Contenuto<\/a>\n                <\/li>\n                            <li class=\"tabs-title idle basic-button default-btns\">\n                    <a href=\"#tabID-block_3bf07619a36f09807803f87fab4e4d06-3\">brightAuthor collegato<\/a>\n                <\/li>\n                    <\/ul><!-- content-tabs -->\n                        <!-- Tabs Content -->\n        <div class=\"tabs-content\" data-tabs-content=\"tabs-tabbed-content-block_3bf07619a36f09807803f87fab4e4d06\">\n            \n                <div class=\"tabs-panel is-active\" id=\"tabID-block_3bf07619a36f09807803f87fab4e4d06-1\">\n\n                    <div class=\"tabs-panel-inner grid-x full-width\">\n\n                                                                                \n                                                            <div class=\"simple-tab-wysiwyg cell small-12 medium-12 large-12 full-width\">\n                                    <p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.brightsign.biz\/wp-content\/uploads\/2025\/04\/bsn.Control_BSN.Cloud-Solution-logo.svg\" alt=\"BrightSign bsn.Control Servizio di configurazione a distanza\" width=\"300\" height=\"300\" \/><\/p>\n<ul>\n<li><strong>Account gratuito:<\/strong> Ogni lettore BrightSign \u00e8 dotato di gestione remota del dispositivo.<\/li>\n<li><strong>Salute del giocatore in tempo reale:<\/strong> Monitorare lo stato e il tempo di attivit\u00e0 dei lettori. Utilizzate i rapporti sullo stato di salute 24 ore su 24 per gestire lo stato di salute delle reti multidispositivo.<\/li>\n<li><strong>Controlli del lettore a distanza:<\/strong> \u00c8 possibile regolare facilmente le impostazioni, eseguire la diagnostica, riavviare i dispositivi e impartire comandi da qualsiasi luogo.<\/li>\n<li><strong>Scelte di CMS versatili:<\/strong> Sfruttate le migliori soluzioni CMS o l'bsn.Content per creare e gestire le presentazioni, con la flessibilit\u00e0 di rifornire in remoto in base all'evoluzione delle esigenze.<\/li>\n<\/ul>\n\n                                                                            <!-- Add CTAs Here -->\n                                                                                    <ul class=\"simple-tab-ctas\">\n                                                                                                        <li class=\"basic-button default\">\n                                                            <a href=\"https:\/\/www.bsn.cloud\/\" target=\"_blank\">\n                                                                CREARE UN ACCOUNT GRATUITO<i class=\"fa-regular fa-file-arrow-down\"><\/i>\n                                                            <\/a>\n                                                        <\/li>\n                                                                                                                                                <\/ul>\n                                                                                                            <\/div>\n                                                                        <\/div><!-- tabs-panel-inner -->\n                <\/div><!-- tabs-panel -->\n            \n                <div class=\"tabs-panel\" id=\"tabID-block_3bf07619a36f09807803f87fab4e4d06-2\">\n\n                    <div class=\"tabs-panel-inner grid-x full-width\">\n\n                                                                                \n                                                            <div class=\"simple-tab-wysiwyg cell small-12 medium-12 large-12 full-width\">\n                                    <p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.brightsign.biz\/wp-content\/uploads\/2025\/04\/bsn.Content_BSN.Cloud-Solution-logo.svg\" alt=\"BrightSign bsn.Content Servizio CMS\" width=\"300\" height=\"300\" \/><\/p>\n<ul>\n<li><b>Potente CMS:<\/b> Sbloccate l'intero contenuto e le capacit\u00e0 di pianificazione di BSN.Cloud con un abbonamento a pagamento.<\/li>\n<li><strong>Gestione dei contenuti:<\/strong> Soluzione connessa al cloud che sblocca tutte le funzionalit\u00e0 del lettore BrightSign per creare, programmare e distribuire presentazioni, gestendo in modo efficiente le librerie di contenuti.<\/li>\n<li><strong>Gestione della rete:<\/strong> Combina le caratteristiche dell'bsn.Control con strumenti per organizzare e gestire in modo efficiente i giocatori con gruppi di rete, tag e report filtrati.<\/li>\n<li><strong>Gestione dei conti:<\/strong> Amministrare l'accesso agli account con strumenti per la gestione di utenti, ruoli, autorizzazioni e abbonamenti ai giocatori per la collaborazione e il coordinamento all'interno del team.<\/li>\n<\/ul>\n\n                                                                            <!-- Add CTAs Here -->\n                                                                                    <ul class=\"simple-tab-ctas\">\n                                                                                                        <li class=\"basic-button default\">\n                                                            <a href=\"https:\/\/www.bsn.cloud\/\" target=\"_blank\">\n                                                                INIZIARE UNA PROVA GRATUITA<i class=\"fa-regular fa-file-arrow-down\"><\/i>\n                                                            <\/a>\n                                                        <\/li>\n                                                                                                                                                <\/ul>\n                                                                                                            <\/div>\n                                                                        <\/div><!-- tabs-panel-inner -->\n                <\/div><!-- tabs-panel -->\n            \n                <div class=\"tabs-panel\" id=\"tabID-block_3bf07619a36f09807803f87fab4e4d06-3\">\n\n                    <div class=\"tabs-panel-inner grid-x full-width\">\n\n                                                                                \n                                                            <div class=\"simple-tab-wysiwyg cell small-12 medium-12 large-12 full-width\">\n                                    <p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.brightsign.biz\/wp-content\/uploads\/2025\/04\/BrightAuthor_BSN.Cloud-Solution-logo.svg\" alt=\"BrightSign brightAuthor gestione connessa del cloud\" width=\"300\" height=\"54\" \/><\/p>\n<ul>\n<li><strong>Software libero:<\/strong> Incluso senza costi aggiuntivi in ogni lettore BrightSign. Configurazione, creazione di presentazioni e accesso ai servizi BSN.Cloud.<\/li>\n<li><strong>Impostazione del lettore remoto:<\/strong> Configurate facilmente lettori singoli o multipli per pubblicare contenuti, compresi i servizi BSN.Cloud e le soluzioni CMS dei partner.<\/li>\n<li><strong>Presentazioni potenti:<\/strong> Create presentazioni semplici o complesse utilizzando tutte le funzioni disponibili dell'BrightSign, compresa l'intelligenza artificiale, grazie a un'interfaccia intuitiva e semplificata.<\/li>\n<li><strong>Console di gestione del cloud:<\/strong> Gestite senza problemi i vostri dispositivi con l'bsn.Control e sbloccate la potenza dell'bsn.Content o di altre soluzioni CMS in un'interfaccia unificata su PC, Mac o Chrome.<\/li>\n<\/ul>\n\n                                                                            <!-- Add CTAs Here -->\n                                                                                    <ul class=\"simple-tab-ctas\">\n                                                                                                        <li class=\"basic-button default\">\n                                                            <a href=\"https:\/\/www.brightsign.biz\/it\/risorse\/download-di-software\/\" target=\"_self\">\n                                                                SCARICA ORA<i class=\"fa-regular fa-file-arrow-down\"><\/i>\n                                                            <\/a>\n                                                        <\/li>\n                                                                                                                                                <\/ul>\n                                                                                                            <\/div>\n                                                                        <\/div><!-- tabs-panel-inner -->\n                <\/div><!-- tabs-panel -->\n                    \n        <\/div><!-- tabs-content -->\n    <\/div><!-- block-inner medium -->\n\n<\/section><!-- tabbed-content -->\n\n\n\n\n<!-- Inject style_attr here -->\n<section\n    id=\"progress-slider-block_c454cdbd9ea9473d719b848b65e9cea7\"\n    class=\"progress-slider custom-block dark small-top medium-bottom\"\n     >\n\n    <div class=\"block-inner\">\n\n                    <div class=\"progress-slider-title\">\n                <h4>Esplora i nostri giocatori<\/h4>\n                            <\/div>\n        \n        <div class=\"swiper progress-swiper\">\n\n            <div class=\"swiper-wrapper\">\n\n                                                            \n                        <div class=\"swiper-slide\">\n\n                                                            <div class=\"prog-slide-image\">\n                                    <img decoding=\"async\" src=\"https:\/\/www.brightsign.biz\/wp-content\/uploads\/2025\/07\/Series-6_HD6_265x272px_reflection_v2.png\" alt=\"BrightSign Lettore di segnaletica digitale HD6\" \/>\n                                <\/div>\n                            \n                                                            <p class=\"xx-small-p\">BrightSign HD6<\/p>\n                            \n                                                            <a class=\"full-button activate-container\" aria-hidden=\"true\" href=\"https:\/\/www.brightsign.biz\/it\/giocatori-brightsign\/serie-6\/hd6\/\" target=\"_self\"><\/a>\n                            \n                        <\/div><!-- .swiper-slide -->\n                                            \n                        <div class=\"swiper-slide\">\n\n                                                            <div class=\"prog-slide-image\">\n                                    <img decoding=\"async\" src=\"https:\/\/www.brightsign.biz\/wp-content\/uploads\/2025\/07\/Series-6_XD6_265x272px_reflection_v2.png\" alt=\"BrightSign Lettore di segnaletica digitale XD6\" \/>\n                                <\/div>\n                            \n                                                            <p class=\"xx-small-p\">BrightSign XD6<\/p>\n                            \n                                                            <a class=\"full-button activate-container\" aria-hidden=\"true\" href=\"https:\/\/www.brightsign.biz\/it\/giocatori-brightsign\/serie-6\/xd6\/\" target=\"_self\"><\/a>\n                            \n                        <\/div><!-- .swiper-slide -->\n                                            \n                        <div class=\"swiper-slide\">\n\n                                                            <div class=\"prog-slide-image\">\n                                    <img decoding=\"async\" src=\"https:\/\/www.brightsign.biz\/wp-content\/uploads\/2023\/03\/XC5-1.png\" alt=\"immagine frontale del prodotto del lettore digital signage BrightSign XC5 su sfondo bianco con ombra\" \/>\n                                <\/div>\n                            \n                                                            <p class=\"xx-small-p\">BrightSign XC5<\/p>\n                            \n                                                            <a class=\"full-button activate-container\" aria-hidden=\"true\" href=\"https:\/\/www.brightsign.biz\/it\/giocatori-brightsign\/serie-5\/xc5\/\" target=\"_self\"><\/a>\n                            \n                        <\/div><!-- .swiper-slide -->\n                                            \n                        <div class=\"swiper-slide\">\n\n                                                            <div class=\"prog-slide-image\">\n                                    <img decoding=\"async\" src=\"https:\/\/www.brightsign.biz\/wp-content\/uploads\/2023\/03\/XT5_Recolor-1.png\" alt=\"immagine frontale del prodotto del lettore digital signage BrightSign XT5 su sfondo bianco con ombra\" \/>\n                                <\/div>\n                            \n                                                            <p class=\"xx-small-p\">BrightSign XT5<\/p>\n                            \n                                                            <a class=\"full-button activate-container\" aria-hidden=\"true\" href=\"https:\/\/www.brightsign.biz\/it\/giocatori-brightsign\/serie-5\/xt5\/\" target=\"_self\"><\/a>\n                            \n                        <\/div><!-- .swiper-slide -->\n                                            \n                        <div class=\"swiper-slide\">\n\n                                                            <div class=\"prog-slide-image\">\n                                    <img decoding=\"async\" src=\"https:\/\/www.brightsign.biz\/wp-content\/uploads\/2023\/03\/XD5-1.png\" alt=\"immagine frontale del prodotto del lettore di segnaletica digitale BrightSign XD5 su sfondo bianco con ombra\" \/>\n                                <\/div>\n                            \n                                                            <p class=\"xx-small-p\">BrightSign XD5<\/p>\n                            \n                                                            <a class=\"full-button activate-container\" aria-hidden=\"true\" href=\"https:\/\/www.brightsign.biz\/it\/giocatori-brightsign\/serie-5\/xd5\/\" target=\"_self\"><\/a>\n                            \n                        <\/div><!-- .swiper-slide -->\n                                            \n                        <div class=\"swiper-slide\">\n\n                                                            <div class=\"prog-slide-image\">\n                                    <img decoding=\"async\" src=\"https:\/\/www.brightsign.biz\/wp-content\/uploads\/2023\/03\/HD5-1.png\" alt=\"immagine frontale del prodotto del lettore digital signage BrightSign HD5 su sfondo bianco con ombra\" \/>\n                                <\/div>\n                            \n                                                            <p class=\"xx-small-p\">BrightSign HD5<\/p>\n                            \n                                                            <a class=\"full-button activate-container\" aria-hidden=\"true\" href=\"https:\/\/www.brightsign.biz\/it\/giocatori-brightsign\/serie-5\/hd5\/\" target=\"_self\"><\/a>\n                            \n                        <\/div><!-- .swiper-slide -->\n                                            \n                        <div class=\"swiper-slide\">\n\n                                                            <div class=\"prog-slide-image\">\n                                    <img decoding=\"async\" src=\"https:\/\/www.brightsign.biz\/wp-content\/uploads\/2023\/03\/LS5-1.png\" alt=\"immagine frontale del prodotto del lettore digital signage BrightSign LS5 su sfondo bianco con ombra\" \/>\n                                <\/div>\n                            \n                                                            <p class=\"xx-small-p\">BrightSign LS5<\/p>\n                            \n                                                            <a class=\"full-button activate-container\" aria-hidden=\"true\" href=\"https:\/\/www.brightsign.biz\/it\/giocatori-brightsign\/serie-5\/ls5\/\" target=\"_self\"><\/a>\n                            \n                        <\/div><!-- .swiper-slide -->\n                                            \n                        <div class=\"swiper-slide\">\n\n                                                            <div class=\"prog-slide-image\">\n                                    <img decoding=\"async\" src=\"https:\/\/www.brightsign.biz\/wp-content\/uploads\/2023\/03\/AU5_Main_White.jpg\" alt=\"immagine frontale del prodotto del lettore audio digitale BrightSign AU5\" \/>\n                                <\/div>\n                            \n                                                            <p class=\"xx-small-p\">BrightSign AU5<\/p>\n                            \n                                                            <a class=\"full-button activate-container\" aria-hidden=\"true\" href=\"https:\/\/www.brightsign.biz\/it\/giocatori-brightsign\/serie-5\/au5\/\" target=\"_self\"><\/a>\n                            \n                        <\/div><!-- .swiper-slide -->\n                                            \n                        <div class=\"swiper-slide\">\n\n                                                            <div class=\"prog-slide-image\">\n                                    <img decoding=\"async\" src=\"https:\/\/www.brightsign.biz\/wp-content\/uploads\/2023\/04\/XT4_TPlayerLineup.jpg\" alt=\"\" \/>\n                                <\/div>\n                            \n                                                            <p class=\"xx-small-p\">BrightSign XT4-T<\/p>\n                            \n                                                            <a class=\"full-button activate-container\" aria-hidden=\"true\" href=\"https:\/\/www.brightsign.biz\/it\/giocatori-brightsign\/serie-4\/\" target=\"_self\"><\/a>\n                            \n                        <\/div><!-- .swiper-slide -->\n                                            \n                        <div class=\"swiper-slide\">\n\n                                                            <div class=\"prog-slide-image\">\n                                    <img decoding=\"async\" src=\"https:\/\/www.brightsign.biz\/wp-content\/uploads\/2023\/04\/XT4_PlayerLineup.jpg\" alt=\"\" \/>\n                                <\/div>\n                            \n                                                            <p class=\"xx-small-p\">BrightSign XT4<\/p>\n                            \n                                                            <a class=\"full-button activate-container\" aria-hidden=\"true\" href=\"https:\/\/www.brightsign.biz\/it\/giocatori-brightsign\/serie-4\/\" target=\"_self\"><\/a>\n                            \n                        <\/div><!-- .swiper-slide -->\n                                    \n            <\/div><!-- .swiper-wrapper -->\n\n            <!-- scrollbar -->\n            <div class=\"swiper-scrollbar\"><\/div>\n            <div class=\"swiper-pagination-wrapper\">\n                <div class=\"swiper-pagination hide\"><\/div>\n            <\/div><!-- .swiper-pagination-wrapper -->\n\n        <\/div><!-- .progress-swiper -->\n\n        \n    <\/div><!-- .block-inner -->\n\n<\/section><!-- .progress-slider -->\n\n\n\n\n\n\n<section id=\"full-width-cta-block_898b9574efbbb14ef05cfb2b007bf55f\" class=\"full-width-cta custom-block\">\n\n<div class=\"block-inner medium grid-x\">\n\n<div class=\"cell small-12 medium-8\">\n    <h4><b>Avete ancora bisogno di aiuto?<\/b><\/h4>\n<p>Non trovi quello che stai cercando? Il nostro team si impegna a trovare la soluzione di digital signage che soddisfi i tuoi obiettivi aziendali e incontri il tuo budget.<\/p>\n<\/div><!-- medium-8 -->\n\n<div class=\"cell small-12 medium-4 content-right\">\n    <div class=\"basic-button blue\"><a href=\"https:\/\/www.brightsign.biz\/it\/contattateci\/\" target=\"_self\">PARLARE CON UN ESPERTO<i class=\"fa-solid fa-chevron-right\"><\/i><\/a><\/div>\n<\/div><!-- medium-4 -->\n\n<\/div><!-- block-inner -->\n\n<\/section><!-- hero -->","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":12248,"parent":539,"menu_order":30,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_searchwp_excluded":"","footnotes":""},"class_list":["post-643","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.brightsign.biz\/it\/wp-json\/wp\/v2\/pages\/643","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brightsign.biz\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.brightsign.biz\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.brightsign.biz\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brightsign.biz\/it\/wp-json\/wp\/v2\/comments?post=643"}],"version-history":[{"count":0,"href":"https:\/\/www.brightsign.biz\/it\/wp-json\/wp\/v2\/pages\/643\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.brightsign.biz\/it\/wp-json\/wp\/v2\/pages\/539"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brightsign.biz\/it\/wp-json\/wp\/v2\/media\/12248"}],"wp:attachment":[{"href":"https:\/\/www.brightsign.biz\/it\/wp-json\/wp\/v2\/media?parent=643"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}